{"id":16291,"date":"2022-12-23T13:58:15","date_gmt":"2022-12-23T12:58:15","guid":{"rendered":"https:\/\/jordibordas.com\/fr\/?p=16291"},"modified":"2022-12-23T13:58:16","modified_gmt":"2022-12-23T12:58:16","slug":"claves-para-un-panettone-perfecto","status":"publish","type":"post","link":"https:\/\/jordibordas.com\/fr\/blog\/claves-para-un-panettone-perfecto\/","title":{"rendered":"Claves para un Panettone perfecto"},"content":{"rendered":"\n<p>Con la Navidad llega nuestro dulce tradicional favorito&#8230; \u00a1el<a href=\"https:\/\/jordibordas.com\/fr\/s\/panettone-de-autor\/\"> <strong>panettone<\/strong><\/a>! \ud83c\udf5e\ud83c\udf84 Se podr\u00eda decir que cada chef tiene su propia <strong>receta de panettone<\/strong>, pero el objetivo siempre es el mismo, que sea tierno, esponjoso y lleno de sabor. <\/p>\n\n\n\n<p>Sin duda, degustar uno con estas caracter\u00edsticas es una experiencia \u00fanica que despierta los cinco sentidos, sobre todo, si est\u00e1 elaborado con<strong> ingredientes de m\u00e1xima calidad, nutritivos y sabrosos.<\/strong> <\/p>\n\n\n\n<p>En este art\u00edculo te desvelamos nuestros trucos mejor guardados para que el resultado sea excelente. \u00a1Empezamos!<\/p>\n\n\n\n<div style=\"height:21px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" style=\"font-size:30px\"><strong>La masa madre<\/strong><\/h2>\n\n\n\n<p><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p>Seguro que has o\u00eddo hablar de la masa madre en alguna ocasi\u00f3n, pero quiz\u00e1s todav\u00eda no sabes lo que es exactamente. Pues bien, <strong>la masa madre es una mezcla de harina y agua que contiene de manera natural un cultivo de bacterias y levaduras.<\/strong> Esta masa hace que el panettone fermente, aportando un aroma inconfundible y muy agradable, y adem\u00e1s garantiza que su textura esponjosa se conserve durante m\u00e1s tiempo. Vamos, \u00a1pura magia!<\/p>\n\n\n\n<p>Cada d\u00eda cortamos una porci\u00f3n de masa madre y le <strong>a\u00f1adimos harina y agua<\/strong> para alimentarla. Esto nos permite mantenerla viva y poder usarla siempre que queramos.<\/p>\n\n\n\n<p>Para nuestro panettone, hacemos lo que llamamos &#8220;<strong>un primer empaste<\/strong>&#8221; con una parte de masa madre, harina, agua, mantequilla, yema de huevo, az\u00facar de coco y panela, y lo dejamos reposar aproximadamente 16 horas hasta que triplica su volumen. <\/p>\n\n\n\n<div style=\"height:21px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/12\/Panettone-masa-madre-trapo-1-819x1024.jpg\" alt=\"\" class=\"wp-image-16614\" srcset=\"https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/12\/Panettone-masa-madre-trapo-1-819x1024.jpg 819w, https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/12\/Panettone-masa-madre-trapo-1-240x300.jpg 240w, https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/12\/Panettone-masa-madre-trapo-1-768x960.jpg 768w, https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/12\/Panettone-masa-madre-trapo-1-80x100.jpg 80w, https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/12\/Panettone-masa-madre-trapo-1-665x831.jpg 665w, https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/12\/Panettone-masa-madre-trapo-1-600x750.jpg 600w, https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/12\/Panettone-masa-madre-trapo-1.jpg 1080w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><figcaption class=\"wp-element-caption\">Conservaci\u00f3n de la masa madre<\/figcaption><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/12\/Panettone-primer-empaste-819x1024.jpg\" alt=\"Panettone-primer-empaste\" class=\"wp-image-16607\" srcset=\"https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/12\/Panettone-primer-empaste-819x1024.jpg 819w, https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/12\/Panettone-primer-empaste-240x300.jpg 240w, https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/12\/Panettone-primer-empaste-768x960.jpg 768w, https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/12\/Panettone-primer-empaste-80x100.jpg 80w, https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/12\/Panettone-primer-empaste-665x831.jpg 665w, https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/12\/Panettone-primer-empaste-600x750.jpg 600w, https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/12\/Panettone-primer-empaste.jpg 1080w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><figcaption class=\"wp-element-caption\">Primer empaste de Panettone<\/figcaption><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading\" style=\"font-size:30px\"><strong>La selecci\u00f3n de los ingredientes<\/strong><\/h2>\n\n\n\n<div style=\"height:17px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Una vez la masa ha fermentado, volvemos a amasar con el resto de ingredientes de la receta.<\/p>\n\n\n\n<p>Como ya hemos adelantado, utilizamos<strong> az\u00facar de coco <\/strong>y<strong> panela<\/strong> que, bajo nuestro punto de vista, aportan un sabor agradable y mejoran el perfil nutricional del panettone. <\/p>\n\n\n\n<p>Por otro lado, adem\u00e1s de utilizar <strong>mantequilla de Normand\u00eda<\/strong> de gran calidad (y esto es imprescindible, ya que el sabor de la mantequilla predomina en la elaboraci\u00f3n), incorporamos <strong>aceite de oliva virgen extra<\/strong> de Enrenou. El AOVE aporta sabor y mejora la textura de la masa una vez cocida. <\/p>\n\n\n\n<p>Junto con la mantequilla a\u00f1adimos rascadura pura de <strong>vainilla de Madagascar<\/strong> (nunca aromas ni extractos). Este toque le da un punto diferencial que nos encanta. <\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/12\/Panettone-azucar-de-coco-819x1024.jpg\" alt=\"Panettone - az\u00facar de coco\" class=\"wp-image-16621\" srcset=\"https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/12\/Panettone-azucar-de-coco-819x1024.jpg 819w, https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/12\/Panettone-azucar-de-coco-240x300.jpg 240w, https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/12\/Panettone-azucar-de-coco-768x960.jpg 768w, https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/12\/Panettone-azucar-de-coco-80x100.jpg 80w, https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/12\/Panettone-azucar-de-coco-665x831.jpg 665w, https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/12\/Panettone-azucar-de-coco-600x750.jpg 600w, https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/12\/Panettone-azucar-de-coco.jpg 1080w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><figcaption class=\"wp-element-caption\">Az\u00facar de coco<\/figcaption><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p>Por \u00faltimo, a\u00f1adimos los ingredientes que determinar\u00e1n la variedad del panettone: <strong>frutas <\/strong>o <strong>chocolate<\/strong>.<\/p>\n\n\n\n<p>Para elaborar un panettone de frutas de calidad, utiliza unas <strong>buenas naranjas <\/strong>que aporten un aroma y unos matices \u00fanicos en tu panettone. Nosotros confitamos las naranjas de Castell\u00f3n utilizando un 50% menos de az\u00facar que el que podr\u00edamos encontrar en la fruta confitada tradicional. Esto es B\u00c1SICO. <\/p>\n\n\n\n<p>Por su parte, en el panettone de chocolate utilizamos una <strong>cobertura bean-to-bar que elaboramos nosotros mismos <\/strong>con cacao org\u00e1nico vegano, az\u00facar de coco y fibra de maiz. Igual que en el de frutas, el chocolate ha de ser de buena calidad, ya que va a estar presente en cada bocado.<\/p>\n\n\n\n<p>Continuando con el proceso, boleamos la masa y dejamos fermentar de nuevo entre 6 a 8 horas m\u00e1s para que el panettone desarrolle todos los aromas caracter\u00edsticos. <\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/12\/Panettone-naranja-confitada-819x1024.jpg\" alt=\"Panettone - naranja confitada\" class=\"wp-image-16623\" srcset=\"https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/12\/Panettone-naranja-confitada-819x1024.jpg 819w, https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/12\/Panettone-naranja-confitada-240x300.jpg 240w, https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/12\/Panettone-naranja-confitada-768x960.jpg 768w, https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/12\/Panettone-naranja-confitada-80x100.jpg 80w, https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/12\/Panettone-naranja-confitada-665x831.jpg 665w, https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/12\/Panettone-naranja-confitada-600x750.jpg 600w, https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/12\/Panettone-naranja-confitada.jpg 1080w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><figcaption class=\"wp-element-caption\">Naranja confitada<\/figcaption><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/12\/Panettone-pasas-sultanas-819x1024.jpg\" alt=\"Panettone - pasas sultanas\" class=\"wp-image-16624\" srcset=\"https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/12\/Panettone-pasas-sultanas-819x1024.jpg 819w, https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/12\/Panettone-pasas-sultanas-240x300.jpg 240w, https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/12\/Panettone-pasas-sultanas-768x960.jpg 768w, https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/12\/Panettone-pasas-sultanas-80x100.jpg 80w, https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/12\/Panettone-pasas-sultanas-665x831.jpg 665w, https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/12\/Panettone-pasas-sultanas-600x750.jpg 600w, https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/12\/Panettone-pasas-sultanas.jpg 1080w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><figcaption class=\"wp-element-caption\">Pasas sultanas<\/figcaption><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/12\/Panettone-masa-frutas-819x1024.jpg\" alt=\"Panettone - masa frutas\" class=\"wp-image-16622\" srcset=\"https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/12\/Panettone-masa-frutas-819x1024.jpg 819w, https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/12\/Panettone-masa-frutas-240x300.jpg 240w, https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/12\/Panettone-masa-frutas-768x960.jpg 768w, https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/12\/Panettone-masa-frutas-80x100.jpg 80w, https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/12\/Panettone-masa-frutas-665x831.jpg 665w, https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/12\/Panettone-masa-frutas-600x750.jpg 600w, https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/12\/Panettone-masa-frutas.jpg 1080w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><figcaption class=\"wp-element-caption\">Masa de panettone de frutas<\/figcaption><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:29px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"745\" height=\"1024\" src=\"https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/12\/panettone-boca-abajo-745x1024.jpg\" alt=\"panettone-boca-abajo\" class=\"wp-image-16334\" srcset=\"https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/12\/panettone-boca-abajo-745x1024.jpg 745w, https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/12\/panettone-boca-abajo-218x300.jpg 218w, https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/12\/panettone-boca-abajo-768x1056.jpg 768w, https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/12\/panettone-boca-abajo-73x100.jpg 73w, https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/12\/panettone-boca-abajo-665x914.jpg 665w, https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/12\/panettone-boca-abajo-600x825.jpg 600w, https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/12\/panettone-boca-abajo.jpg 1080w\" sizes=\"auto, (max-width: 745px) 100vw, 745px\" \/><figcaption class=\"wp-element-caption\">Panettone reci\u00e9n salido del horno<\/figcaption><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading\" style=\"font-size:30px\">El horneado<\/h2>\n\n\n\n<p>Por \u00faltimo, cubrimos los panettone con la <strong>gama crujiente de panela<\/strong>, sustituyendo de esta manera el t\u00edpico az\u00facar perlado que recubre los panettone cl\u00e1sicos.<\/p>\n\n\n\n<p>Damos el toque final a\u00f1adi\u00e9ndole <strong>frutos secos<\/strong> y \u00a1a cocer en el horno!<\/p>\n\n\n\n<p>Nosotros utilizamos nuestros hornos del obrador familiar, que tienen m\u00e1s de 30 a\u00f1os y nunca nos han fallado. <\/p>\n\n\n\n<p>Una vez horneados, comprobamos que tienen la temperatura adecuada y los colocamos boca abajo para dejarlos enfriar hasta su envasado.<\/p>\n\n\n\n<p>Con esta t\u00e9cnica, conservamos el<strong> volumen <\/strong>y la <strong>esponjosidad.<\/strong><\/p>\n\n\n\n<p>Como puedes comprobar, cuidamos y mimamos todos los detalles del proceso de elaboraci\u00f3n para que tengas una experiencia \u00fanica.<\/p>\n<\/div>\n<\/div>\n\n\n\n<p>En este art\u00edculo hemos intentado plasmar el amor y cari\u00f1o que ponemos en la elaboraci\u00f3n de nuestros <a href=\"https:\/\/jordibordas.com\/fr\/s\/panettone-de-autor\/\">panettones<\/a>, pero para que lo veas con tus propios ojos, tambi\u00e9n hemos preparado un reportaje en el que Jordi explica detalladamente todo este proceso. \u00a1Esperamos que lo disfrutes! <\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Claves para un Panettone perfecto\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/bz12_LJyAeE?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con la Navidad llega nuestro dulce tradicional favorito&#8230; \u00a1el panettone! \ud83c\udf5e\ud83c\udf84 Se podr\u00eda decir que cada chef tiene su propia receta de panettone, pero el objetivo siempre es el mismo, que sea tierno, esponjoso y lleno de sabor. Sin duda, degustar uno con estas caracter\u00edsticas es una experiencia \u00fanica que despierta los cinco sentidos, sobre [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":16324,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[7,1531],"tags":[25,84,62,71],"class_list":["post-16291","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-recetas","category-reportajes","tag-ingredientes-de-pasteleria","tag-masterclass-de-pasteleria","tag-recetas-de-pasteleria","tag-tecnicas-de-pasteleria"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Claves para un Panettone perfecto - Jordi Bordas \u00c9cole de P\u00e2tisserie<\/title>\n<meta name=\"description\" content=\"Damos inicio a la \u00e9poca m\u00e1s m\u00e1gica del a\u00f1o, la Navidad, y con ella a nuestro dulce tradicional favorito; \u00a1el Panettone!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jordibordas.com\/fr\/blog\/claves-para-un-panettone-perfecto\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Claves para un Panettone perfecto - Jordi Bordas \u00c9cole de P\u00e2tisserie\" \/>\n<meta property=\"og:description\" content=\"Damos inicio a la \u00e9poca m\u00e1s m\u00e1gica del a\u00f1o, la Navidad, y con ella a nuestro dulce tradicional favorito; \u00a1el Panettone!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jordibordas.com\/fr\/blog\/claves-para-un-panettone-perfecto\/\" \/>\n<meta property=\"og:site_name\" content=\"Jordi Bordas \u00c9cole de P\u00e2tisserie\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-23T12:58:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-23T12:58:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/12\/panettone-portada.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"876\" \/>\n\t<meta property=\"og:image:height\" content=\"506\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jordi Bordas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jordi Bordas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/blog\\\/claves-para-un-panettone-perfecto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/blog\\\/claves-para-un-panettone-perfecto\\\/\"},\"author\":{\"name\":\"Jordi Bordas\",\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/#\\\/schema\\\/person\\\/e258d3dedfb9998c9338c0ee02ecf429\"},\"headline\":\"Claves para un Panettone perfecto\",\"datePublished\":\"2022-12-23T12:58:15+00:00\",\"dateModified\":\"2022-12-23T12:58:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/blog\\\/claves-para-un-panettone-perfecto\\\/\"},\"wordCount\":713,\"publisher\":{\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/blog\\\/claves-para-un-panettone-perfecto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/12\\\/panettone-portada.jpg\",\"keywords\":[\"INGREDIENTES DE PASTELER\u00cdA\",\"MASTERCLASS DE PASTELER\u00cdA\",\"RECETAS DE PASTELER\u00cdA\",\"T\u00c9CNICAS DE PASTELER\u00cdA\"],\"articleSection\":[\"Recetas\",\"REPORTAJES\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/blog\\\/claves-para-un-panettone-perfecto\\\/\",\"url\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/blog\\\/claves-para-un-panettone-perfecto\\\/\",\"name\":\"Claves para un Panettone perfecto - Jordi Bordas \u00c9cole de P\u00e2tisserie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/blog\\\/claves-para-un-panettone-perfecto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/blog\\\/claves-para-un-panettone-perfecto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/12\\\/panettone-portada.jpg\",\"datePublished\":\"2022-12-23T12:58:15+00:00\",\"dateModified\":\"2022-12-23T12:58:16+00:00\",\"description\":\"Damos inicio a la \u00e9poca m\u00e1s m\u00e1gica del a\u00f1o, la Navidad, y con ella a nuestro dulce tradicional favorito; \u00a1el Panettone!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/blog\\\/claves-para-un-panettone-perfecto\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jordibordas.com\\\/fr\\\/blog\\\/claves-para-un-panettone-perfecto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/blog\\\/claves-para-un-panettone-perfecto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/12\\\/panettone-portada.jpg\",\"contentUrl\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/12\\\/panettone-portada.jpg\",\"width\":876,\"height\":506},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/blog\\\/claves-para-un-panettone-perfecto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Claves para un Panettone perfecto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/\",\"name\":\"Jordi Bordas \u00c9cole de P\u00e2tisserie\",\"description\":\"Innovative Pastry Education\",\"publisher\":{\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/#organization\",\"name\":\"Jordi Bordas\",\"url\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2020\\\/11\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2020\\\/11\\\/logo.svg\",\"width\":274,\"height\":68,\"caption\":\"Jordi Bordas\"},\"image\":{\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/#\\\/schema\\\/person\\\/e258d3dedfb9998c9338c0ee02ecf429\",\"name\":\"Jordi Bordas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e834c88a47f9e573e74d3dcf46636654875c577e557d6d4e85dd5c58bccd37b2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e834c88a47f9e573e74d3dcf46636654875c577e557d6d4e85dd5c58bccd37b2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e834c88a47f9e573e74d3dcf46636654875c577e557d6d4e85dd5c58bccd37b2?s=96&d=mm&r=g\",\"caption\":\"Jordi Bordas\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Claves para un Panettone perfecto - Jordi Bordas \u00c9cole de P\u00e2tisserie","description":"Damos inicio a la \u00e9poca m\u00e1s m\u00e1gica del a\u00f1o, la Navidad, y con ella a nuestro dulce tradicional favorito; \u00a1el Panettone!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jordibordas.com\/fr\/blog\/claves-para-un-panettone-perfecto\/","og_locale":"fr_FR","og_type":"article","og_title":"Claves para un Panettone perfecto - Jordi Bordas \u00c9cole de P\u00e2tisserie","og_description":"Damos inicio a la \u00e9poca m\u00e1s m\u00e1gica del a\u00f1o, la Navidad, y con ella a nuestro dulce tradicional favorito; \u00a1el Panettone!","og_url":"https:\/\/jordibordas.com\/fr\/blog\/claves-para-un-panettone-perfecto\/","og_site_name":"Jordi Bordas \u00c9cole de P\u00e2tisserie","article_published_time":"2022-12-23T12:58:15+00:00","article_modified_time":"2022-12-23T12:58:16+00:00","og_image":[{"width":876,"height":506,"url":"https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/12\/panettone-portada.jpg","type":"image\/jpeg"}],"author":"Jordi Bordas","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Jordi Bordas","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jordibordas.com\/fr\/blog\/claves-para-un-panettone-perfecto\/#article","isPartOf":{"@id":"https:\/\/jordibordas.com\/fr\/blog\/claves-para-un-panettone-perfecto\/"},"author":{"name":"Jordi Bordas","@id":"https:\/\/jordibordas.com\/fr\/#\/schema\/person\/e258d3dedfb9998c9338c0ee02ecf429"},"headline":"Claves para un Panettone perfecto","datePublished":"2022-12-23T12:58:15+00:00","dateModified":"2022-12-23T12:58:16+00:00","mainEntityOfPage":{"@id":"https:\/\/jordibordas.com\/fr\/blog\/claves-para-un-panettone-perfecto\/"},"wordCount":713,"publisher":{"@id":"https:\/\/jordibordas.com\/fr\/#organization"},"image":{"@id":"https:\/\/jordibordas.com\/fr\/blog\/claves-para-un-panettone-perfecto\/#primaryimage"},"thumbnailUrl":"https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/12\/panettone-portada.jpg","keywords":["INGREDIENTES DE PASTELER\u00cdA","MASTERCLASS DE PASTELER\u00cdA","RECETAS DE PASTELER\u00cdA","T\u00c9CNICAS DE PASTELER\u00cdA"],"articleSection":["Recetas","REPORTAJES"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/jordibordas.com\/fr\/blog\/claves-para-un-panettone-perfecto\/","url":"https:\/\/jordibordas.com\/fr\/blog\/claves-para-un-panettone-perfecto\/","name":"Claves para un Panettone perfecto - Jordi Bordas \u00c9cole de P\u00e2tisserie","isPartOf":{"@id":"https:\/\/jordibordas.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jordibordas.com\/fr\/blog\/claves-para-un-panettone-perfecto\/#primaryimage"},"image":{"@id":"https:\/\/jordibordas.com\/fr\/blog\/claves-para-un-panettone-perfecto\/#primaryimage"},"thumbnailUrl":"https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/12\/panettone-portada.jpg","datePublished":"2022-12-23T12:58:15+00:00","dateModified":"2022-12-23T12:58:16+00:00","description":"Damos inicio a la \u00e9poca m\u00e1s m\u00e1gica del a\u00f1o, la Navidad, y con ella a nuestro dulce tradicional favorito; \u00a1el Panettone!","breadcrumb":{"@id":"https:\/\/jordibordas.com\/fr\/blog\/claves-para-un-panettone-perfecto\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jordibordas.com\/fr\/blog\/claves-para-un-panettone-perfecto\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/jordibordas.com\/fr\/blog\/claves-para-un-panettone-perfecto\/#primaryimage","url":"https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/12\/panettone-portada.jpg","contentUrl":"https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/12\/panettone-portada.jpg","width":876,"height":506},{"@type":"BreadcrumbList","@id":"https:\/\/jordibordas.com\/fr\/blog\/claves-para-un-panettone-perfecto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/jordibordas.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Claves para un Panettone perfecto"}]},{"@type":"WebSite","@id":"https:\/\/jordibordas.com\/fr\/#website","url":"https:\/\/jordibordas.com\/fr\/","name":"Jordi Bordas \u00c9cole de P\u00e2tisserie","description":"Innovative Pastry Education","publisher":{"@id":"https:\/\/jordibordas.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jordibordas.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/jordibordas.com\/fr\/#organization","name":"Jordi Bordas","url":"https:\/\/jordibordas.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/jordibordas.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2020\/11\/logo.svg","contentUrl":"https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2020\/11\/logo.svg","width":274,"height":68,"caption":"Jordi Bordas"},"image":{"@id":"https:\/\/jordibordas.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/jordibordas.com\/fr\/#\/schema\/person\/e258d3dedfb9998c9338c0ee02ecf429","name":"Jordi Bordas","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/e834c88a47f9e573e74d3dcf46636654875c577e557d6d4e85dd5c58bccd37b2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e834c88a47f9e573e74d3dcf46636654875c577e557d6d4e85dd5c58bccd37b2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e834c88a47f9e573e74d3dcf46636654875c577e557d6d4e85dd5c58bccd37b2?s=96&d=mm&r=g","caption":"Jordi Bordas"}}]}},"_links":{"self":[{"href":"https:\/\/jordibordas.com\/fr\/wp-json\/wp\/v2\/posts\/16291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jordibordas.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jordibordas.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jordibordas.com\/fr\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/jordibordas.com\/fr\/wp-json\/wp\/v2\/comments?post=16291"}],"version-history":[{"count":79,"href":"https:\/\/jordibordas.com\/fr\/wp-json\/wp\/v2\/posts\/16291\/revisions"}],"predecessor-version":[{"id":16900,"href":"https:\/\/jordibordas.com\/fr\/wp-json\/wp\/v2\/posts\/16291\/revisions\/16900"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jordibordas.com\/fr\/wp-json\/wp\/v2\/media\/16324"}],"wp:attachment":[{"href":"https:\/\/jordibordas.com\/fr\/wp-json\/wp\/v2\/media?parent=16291"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jordibordas.com\/fr\/wp-json\/wp\/v2\/categories?post=16291"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jordibordas.com\/fr\/wp-json\/wp\/v2\/tags?post=16291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}