{"id":4319,"date":"2021-05-14T09:49:42","date_gmt":"2021-05-14T09:49:42","guid":{"rendered":"https:\/\/jordibordas.com\/fr\/?p=4319"},"modified":"2022-09-12T13:49:59","modified_gmt":"2022-09-12T11:49:59","slug":"como-utilizar-los-lacteos-en-recetas-de-pasteleria","status":"publish","type":"post","link":"https:\/\/jordibordas.com\/fr\/blog\/como-utilizar-los-lacteos-en-recetas-de-pasteleria\/","title":{"rendered":"C\u00f3mo utilizar los l\u00e1cteos en recetas de pasteler\u00eda"},"content":{"rendered":"\n<p>Cuando trabajamos con los l\u00e1cteos en recetas de pasteler\u00eda como sabor principal en una elaboraci\u00f3n, hay ciertos par\u00e1metros que debemos tener en cuenta si queremos obtener texturas estables y perfectamente equilibradas, entre ellos la <strong>cremosidad<\/strong>, la<strong> textura<\/strong> y el <strong>sabor<\/strong>.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:60%\">\n<p>Ya hemos hablado varias veces de la importancia de controlar las <strong>t\u00e9cnicas<\/strong> de creaci\u00f3n de texturas en recetas de pasteler\u00eda, pues es determinante a la hora de crear una experiencia de degustaci\u00f3n \u00f3ptima. Esto es algo que tratamos en profundidad en el <a href=\"https:\/\/jordibordas.com\/fr\/curso-online-de-pasteleria-bconcept\/\">Curso de Pasteler\u00eda B\u00b7Concept online y extendido<\/a>, junto con el conocimiento de las <strong>mol\u00e9culas <\/strong>y el dominio de la <strong>formulaci\u00f3n<\/strong> de recetas.<\/p>\n\n\n\n<p>En la masterclass que realizamos el pasado 16 de marzo pudimos dar algunas pinceladas sobre estos par\u00e1metros, utilizando los ingredientes l\u00e1cteos como hilo conductor.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2021\/05\/Grafico-parametros-lacteos-1-1024x1024.jpg\" alt=\"\" class=\"wp-image-4324\" width=\"256\" height=\"256\" srcset=\"https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2021\/05\/Grafico-parametros-lacteos-1-1024x1024.jpg 1024w, https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2021\/05\/Grafico-parametros-lacteos-1-300x300.jpg 300w, https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2021\/05\/Grafico-parametros-lacteos-1-150x150.jpg 150w, https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2021\/05\/Grafico-parametros-lacteos-1-768x768.jpg 768w, https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2021\/05\/Grafico-parametros-lacteos-1-1536x1536.jpg 1536w, https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2021\/05\/Grafico-parametros-lacteos-1-2048x2048.jpg 2048w, https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2021\/05\/Grafico-parametros-lacteos-1-2000x2000.jpg 2000w, https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2021\/05\/Grafico-parametros-lacteos-1-1330x1330.jpg 1330w, https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2021\/05\/Grafico-parametros-lacteos-1-665x665.jpg 665w, https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2021\/05\/Grafico-parametros-lacteos-1-600x600.jpg 600w, https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2021\/05\/Grafico-parametros-lacteos-1-100x100.jpg 100w\" sizes=\"auto, (max-width: 256px) 100vw, 256px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p>Iniciamos el seminario pregunt\u00e1ndoos cu\u00e1les eran los problemas m\u00e1s habituales que encontrabais al utilizar l\u00e1cteos en las recetas, algunas de las respuestas fueron:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Texturas cortadas o granuladas.<\/li><li>Problemas al mezclar l\u00e1cteos, como el yogur, con frutas \u00e1cidas.<\/li><li>\u200bDificultad para estabilizar recetas con l\u00e1cteos y alcohol.<\/li><li>Problemas al descongelar.<\/li><li>Sin\u00e9resis en tartas de queso hornadas.<\/li><\/ul>\n\n\n\n<p>Adem\u00e1s de dar respuesta a estas cuestiones, durante la masterclass os explicamos c\u00f3mo utilizar correctamente esta familia de ingredientes, entre ellos el Cream Cheese o el Mascarpone de <a href=\"https:\/\/www.elle-et-vire.com\/pro\/en\/\" target=\"_blank\" rel=\"noreferrer noopener\">Elle &amp; Vire<\/a>, a trav\u00e9s de las <strong>recetas de tiramis\u00fa y cheesecake<\/strong>.<\/p>\n\n\n\n<p>\u00bfTe quedaste con las ganas de verlo? \u00a1No te preocupes! Te dejamos a continuaci\u00f3n la masterclass completa en espa\u00f1ol y el dossier de recetas para que puedas poner en pr\u00e1ctica todo lo aprendido. <\/p>\n\n\n\n<div style=\"height:21px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Receta de Cheesecake y Tiramis\u00fa. Utilizar l\u00e1cteos en pasteler\u00eda \u2013 MASTERCLASS\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/O4LiywImsLM?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-width wp-block-button__width-50 has-custom-font-size has-small-font-size\"><a class=\"wp-block-button__link has-background\" href=\"https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2021\/05\/Recetario-Elleetvire-Jordi-Bordas-2021.pdf\" style=\"border-radius:0px;background-color:#d5a678\">DESGARGAR RECETARIO<\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>\u00a1Nos vemos en la pr\u00f3xima!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuando trabajamos con los l\u00e1cteos en recetas de pasteler\u00eda como sabor principal en una elaboraci\u00f3n, hay ciertos par\u00e1metros que debemos tener en cuenta si queremos obtener texturas estables y perfectamente equilibradas, entre ellos la cremosidad, la textura y el sabor. Ya hemos hablado varias veces de la importancia de controlar las t\u00e9cnicas de creaci\u00f3n de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":4332,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[38,7],"tags":[78,25,84,71],"class_list":["post-4319","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventos","category-recetas","tag-cremosidad","tag-ingredientes-de-pasteleria","tag-masterclass-de-pasteleria","tag-tecnicas-de-pasteleria"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>C\u00f3mo utilizar los l\u00e1cteos en recetas de pasteler\u00eda - Jordi Bordas \u00c9cole de P\u00e2tisserie<\/title>\n<meta name=\"description\" content=\"\u00bfTrabajas con l\u00e1cteos en tus recetas de pasteler\u00eda como sabor principal? Hay ciertos par\u00e1metros que debes tener en cuenta.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jordibordas.com\/fr\/blog\/como-utilizar-los-lacteos-en-recetas-de-pasteleria\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f3mo utilizar los l\u00e1cteos en recetas de pasteler\u00eda - Jordi Bordas \u00c9cole de P\u00e2tisserie\" \/>\n<meta property=\"og:description\" content=\"\u00bfTrabajas con l\u00e1cteos en tus recetas de pasteler\u00eda como sabor principal? Hay ciertos par\u00e1metros que debes tener en cuenta.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jordibordas.com\/fr\/blog\/como-utilizar-los-lacteos-en-recetas-de-pasteleria\/\" \/>\n<meta property=\"og:site_name\" content=\"Jordi Bordas \u00c9cole de P\u00e2tisserie\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-14T09:49:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-12T11:49:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2021\/05\/Receta-Tiramisu-Mascarpone.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"876\" \/>\n\t<meta property=\"og:image:height\" content=\"506\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marta\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marta\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/blog\\\/como-utilizar-los-lacteos-en-recetas-de-pasteleria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/blog\\\/como-utilizar-los-lacteos-en-recetas-de-pasteleria\\\/\"},\"author\":{\"name\":\"Marta\",\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/#\\\/schema\\\/person\\\/ab762e8d24eeb55f78f4a4831dfa29fe\"},\"headline\":\"C\u00f3mo utilizar los l\u00e1cteos en recetas de pasteler\u00eda\",\"datePublished\":\"2021-05-14T09:49:42+00:00\",\"dateModified\":\"2022-09-12T11:49:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/blog\\\/como-utilizar-los-lacteos-en-recetas-de-pasteleria\\\/\"},\"wordCount\":308,\"publisher\":{\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/blog\\\/como-utilizar-los-lacteos-en-recetas-de-pasteleria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2021\\\/05\\\/Receta-Tiramisu-Mascarpone.jpg\",\"keywords\":[\"CREMOSIDAD\",\"INGREDIENTES DE PASTELER\u00cdA\",\"MASTERCLASS DE PASTELER\u00cdA\",\"T\u00c9CNICAS DE PASTELER\u00cdA\"],\"articleSection\":[\"Eventos\",\"Recetas\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/blog\\\/como-utilizar-los-lacteos-en-recetas-de-pasteleria\\\/\",\"url\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/blog\\\/como-utilizar-los-lacteos-en-recetas-de-pasteleria\\\/\",\"name\":\"C\u00f3mo utilizar los l\u00e1cteos en recetas de pasteler\u00eda - Jordi Bordas \u00c9cole de P\u00e2tisserie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/blog\\\/como-utilizar-los-lacteos-en-recetas-de-pasteleria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/blog\\\/como-utilizar-los-lacteos-en-recetas-de-pasteleria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2021\\\/05\\\/Receta-Tiramisu-Mascarpone.jpg\",\"datePublished\":\"2021-05-14T09:49:42+00:00\",\"dateModified\":\"2022-09-12T11:49:59+00:00\",\"description\":\"\u00bfTrabajas con l\u00e1cteos en tus recetas de pasteler\u00eda como sabor principal? Hay ciertos par\u00e1metros que debes tener en cuenta.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/blog\\\/como-utilizar-los-lacteos-en-recetas-de-pasteleria\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jordibordas.com\\\/fr\\\/blog\\\/como-utilizar-los-lacteos-en-recetas-de-pasteleria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/blog\\\/como-utilizar-los-lacteos-en-recetas-de-pasteleria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2021\\\/05\\\/Receta-Tiramisu-Mascarpone.jpg\",\"contentUrl\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2021\\\/05\\\/Receta-Tiramisu-Mascarpone.jpg\",\"width\":876,\"height\":506},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/blog\\\/como-utilizar-los-lacteos-en-recetas-de-pasteleria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"C\u00f3mo utilizar los l\u00e1cteos en recetas de pasteler\u00eda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/\",\"name\":\"Jordi Bordas \u00c9cole de P\u00e2tisserie\",\"description\":\"Innovative Pastry Education\",\"publisher\":{\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/#organization\",\"name\":\"Jordi Bordas\",\"url\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2020\\\/11\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2020\\\/11\\\/logo.svg\",\"width\":274,\"height\":68,\"caption\":\"Jordi Bordas\"},\"image\":{\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/#\\\/schema\\\/person\\\/ab762e8d24eeb55f78f4a4831dfa29fe\",\"name\":\"Marta\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e681e4aec92ef304d8f3984d242a11654fb14cf41d5d9a672d7d6ff9b7be0d54?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e681e4aec92ef304d8f3984d242a11654fb14cf41d5d9a672d7d6ff9b7be0d54?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e681e4aec92ef304d8f3984d242a11654fb14cf41d5d9a672d7d6ff9b7be0d54?s=96&d=mm&r=g\",\"caption\":\"Marta\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00f3mo utilizar los l\u00e1cteos en recetas de pasteler\u00eda - Jordi Bordas \u00c9cole de P\u00e2tisserie","description":"\u00bfTrabajas con l\u00e1cteos en tus recetas de pasteler\u00eda como sabor principal? Hay ciertos par\u00e1metros que debes tener en cuenta.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jordibordas.com\/fr\/blog\/como-utilizar-los-lacteos-en-recetas-de-pasteleria\/","og_locale":"fr_FR","og_type":"article","og_title":"C\u00f3mo utilizar los l\u00e1cteos en recetas de pasteler\u00eda - Jordi Bordas \u00c9cole de P\u00e2tisserie","og_description":"\u00bfTrabajas con l\u00e1cteos en tus recetas de pasteler\u00eda como sabor principal? Hay ciertos par\u00e1metros que debes tener en cuenta.","og_url":"https:\/\/jordibordas.com\/fr\/blog\/como-utilizar-los-lacteos-en-recetas-de-pasteleria\/","og_site_name":"Jordi Bordas \u00c9cole de P\u00e2tisserie","article_published_time":"2021-05-14T09:49:42+00:00","article_modified_time":"2022-09-12T11:49:59+00:00","og_image":[{"width":876,"height":506,"url":"https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2021\/05\/Receta-Tiramisu-Mascarpone.jpg","type":"image\/jpeg"}],"author":"Marta","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Marta","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jordibordas.com\/fr\/blog\/como-utilizar-los-lacteos-en-recetas-de-pasteleria\/#article","isPartOf":{"@id":"https:\/\/jordibordas.com\/fr\/blog\/como-utilizar-los-lacteos-en-recetas-de-pasteleria\/"},"author":{"name":"Marta","@id":"https:\/\/jordibordas.com\/fr\/#\/schema\/person\/ab762e8d24eeb55f78f4a4831dfa29fe"},"headline":"C\u00f3mo utilizar los l\u00e1cteos en recetas de pasteler\u00eda","datePublished":"2021-05-14T09:49:42+00:00","dateModified":"2022-09-12T11:49:59+00:00","mainEntityOfPage":{"@id":"https:\/\/jordibordas.com\/fr\/blog\/como-utilizar-los-lacteos-en-recetas-de-pasteleria\/"},"wordCount":308,"publisher":{"@id":"https:\/\/jordibordas.com\/fr\/#organization"},"image":{"@id":"https:\/\/jordibordas.com\/fr\/blog\/como-utilizar-los-lacteos-en-recetas-de-pasteleria\/#primaryimage"},"thumbnailUrl":"https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2021\/05\/Receta-Tiramisu-Mascarpone.jpg","keywords":["CREMOSIDAD","INGREDIENTES DE PASTELER\u00cdA","MASTERCLASS DE PASTELER\u00cdA","T\u00c9CNICAS DE PASTELER\u00cdA"],"articleSection":["Eventos","Recetas"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/jordibordas.com\/fr\/blog\/como-utilizar-los-lacteos-en-recetas-de-pasteleria\/","url":"https:\/\/jordibordas.com\/fr\/blog\/como-utilizar-los-lacteos-en-recetas-de-pasteleria\/","name":"C\u00f3mo utilizar los l\u00e1cteos en recetas de pasteler\u00eda - Jordi Bordas \u00c9cole de P\u00e2tisserie","isPartOf":{"@id":"https:\/\/jordibordas.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jordibordas.com\/fr\/blog\/como-utilizar-los-lacteos-en-recetas-de-pasteleria\/#primaryimage"},"image":{"@id":"https:\/\/jordibordas.com\/fr\/blog\/como-utilizar-los-lacteos-en-recetas-de-pasteleria\/#primaryimage"},"thumbnailUrl":"https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2021\/05\/Receta-Tiramisu-Mascarpone.jpg","datePublished":"2021-05-14T09:49:42+00:00","dateModified":"2022-09-12T11:49:59+00:00","description":"\u00bfTrabajas con l\u00e1cteos en tus recetas de pasteler\u00eda como sabor principal? Hay ciertos par\u00e1metros que debes tener en cuenta.","breadcrumb":{"@id":"https:\/\/jordibordas.com\/fr\/blog\/como-utilizar-los-lacteos-en-recetas-de-pasteleria\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jordibordas.com\/fr\/blog\/como-utilizar-los-lacteos-en-recetas-de-pasteleria\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/jordibordas.com\/fr\/blog\/como-utilizar-los-lacteos-en-recetas-de-pasteleria\/#primaryimage","url":"https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2021\/05\/Receta-Tiramisu-Mascarpone.jpg","contentUrl":"https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2021\/05\/Receta-Tiramisu-Mascarpone.jpg","width":876,"height":506},{"@type":"BreadcrumbList","@id":"https:\/\/jordibordas.com\/fr\/blog\/como-utilizar-los-lacteos-en-recetas-de-pasteleria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/jordibordas.com\/fr\/"},{"@type":"ListItem","position":2,"name":"C\u00f3mo utilizar los l\u00e1cteos en recetas de pasteler\u00eda"}]},{"@type":"WebSite","@id":"https:\/\/jordibordas.com\/fr\/#website","url":"https:\/\/jordibordas.com\/fr\/","name":"Jordi Bordas \u00c9cole de P\u00e2tisserie","description":"Innovative Pastry Education","publisher":{"@id":"https:\/\/jordibordas.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jordibordas.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/jordibordas.com\/fr\/#organization","name":"Jordi Bordas","url":"https:\/\/jordibordas.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/jordibordas.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2020\/11\/logo.svg","contentUrl":"https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2020\/11\/logo.svg","width":274,"height":68,"caption":"Jordi Bordas"},"image":{"@id":"https:\/\/jordibordas.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/jordibordas.com\/fr\/#\/schema\/person\/ab762e8d24eeb55f78f4a4831dfa29fe","name":"Marta","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/e681e4aec92ef304d8f3984d242a11654fb14cf41d5d9a672d7d6ff9b7be0d54?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e681e4aec92ef304d8f3984d242a11654fb14cf41d5d9a672d7d6ff9b7be0d54?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e681e4aec92ef304d8f3984d242a11654fb14cf41d5d9a672d7d6ff9b7be0d54?s=96&d=mm&r=g","caption":"Marta"}}]}},"_links":{"self":[{"href":"https:\/\/jordibordas.com\/fr\/wp-json\/wp\/v2\/posts\/4319","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jordibordas.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jordibordas.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jordibordas.com\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/jordibordas.com\/fr\/wp-json\/wp\/v2\/comments?post=4319"}],"version-history":[{"count":15,"href":"https:\/\/jordibordas.com\/fr\/wp-json\/wp\/v2\/posts\/4319\/revisions"}],"predecessor-version":[{"id":12208,"href":"https:\/\/jordibordas.com\/fr\/wp-json\/wp\/v2\/posts\/4319\/revisions\/12208"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jordibordas.com\/fr\/wp-json\/wp\/v2\/media\/4332"}],"wp:attachment":[{"href":"https:\/\/jordibordas.com\/fr\/wp-json\/wp\/v2\/media?parent=4319"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jordibordas.com\/fr\/wp-json\/wp\/v2\/categories?post=4319"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jordibordas.com\/fr\/wp-json\/wp\/v2\/tags?post=4319"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}