{"id":6210,"date":"2021-11-05T12:39:47","date_gmt":"2021-11-05T11:39:47","guid":{"rendered":"https:\/\/jordibordas.com\/fr\/?p=6210"},"modified":"2022-09-14T09:30:29","modified_gmt":"2022-09-14T07:30:29","slug":"receta-de-pumkin-cake-vegano-y-sin-gluten","status":"publish","type":"post","link":"https:\/\/jordibordas.com\/fr\/blog\/receta-de-pumkin-cake-vegano-y-sin-gluten\/","title":{"rendered":"Receta de Pumpkin Cake vegano y sin gluten"},"content":{"rendered":"\n<p>\u00bfTe han sobrado calabazas de Halloween y no sabes qu\u00e9 hacer con ellas? Te proponemos este Pumpkin Cake s\u00faper jugoso y arom\u00e1tico para que aproveches este fant\u00e1stico fruto de temporada.<\/p>\n\n\n\n<p>Se trata de una elaboraci\u00f3n sin gluten y 100% vegana, y los ingredientes son muy f\u00e1ciles de conseguir: calabaza, nueces de pecan, aceite de oliva, az\u00facar de coco, harina de almendra y de arroz, almid\u00f3n de ma\u00edz, impulsor, sal y 5 especias.<\/p>\n\n\n\n<p>Confesamos que los cakes veganos son todav\u00eda un reto para nosotros, por lo que nos encantar\u00eda que hicieras esta receta en casa y nos contaras qu\u00e9 te ha parecido. \u00a1Toda aportaci\u00f3n ser\u00e1 bienvenida!<\/p>\n\n\n\n<div style=\"height:23px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\">\n<p><strong>INGREDIENTES<\/strong><\/p>\n\n\n\n<p class=\"has-cyan-bluish-gray-color has-text-color has-small-font-size\">95 g Pec\u00e1n entero<br>468 g Pur\u00e9 de calabaza<br>95 g Aceite de oliva<br>107 g Az\u00facar de coco<br>76 g Harina de almendra<br>95 g Harina de arroz integral<br>48 g Almid\u00f3n de ma\u00edz<br>11 g Impulsor<br>3 g Mezcla de 5 especias<br>2 g Sal<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p><strong>ELABORACI\u00d3N<\/strong><\/p>\n\n\n\n<p class=\"has-small-font-size\">Lavar y colar los pecanes. Tostar durante 10 minutos a 170 \u00baC en un horno est\u00e1tico o a 150 \u00baC en un horno ventilado, dejando la puerta ligeramente entreabierta para que salga el vapor. Enfriar y cortar a trozos irregulares.<\/p>\n\n\n\n<p class=\"has-small-font-size\">Lavar y pelar una calabaza. Cortar una rodaja fina de la parte que contiene las semillas y reservar. Retirar las semillas del resto de la calabaza y cortar a dados de unos 2 x 2 cm. Cocer en abundante agua salada durante 20 minutos, colar, triturar y pesar la cantidad necesaria para la receta (468 g).<\/p>\n\n\n\n<p class=\"has-small-font-size\">Mezclar el pur\u00e9 y el aceite con el t\u00farmix. A\u00f1adir el az\u00facar y la harina de almendra y trabajar intensamente con el t\u00farmix.<\/p>\n\n\n\n<p class=\"has-small-font-size\">Tamizar juntos la harina de arroz, el almid\u00f3n de ma\u00edz, el impulsor y las especias, a\u00f1adir, junto con la sal, a la mezcla anterior y trabajar con el t\u00farmix hasta obtener una masa homog\u00e9nea.<\/p>\n\n\n\n<p class=\"has-small-font-size\">Incorporar los pecanes cortados con la ayuda de una esp\u00e1tula de goma.<\/p>\n\n\n\n<p class=\"has-small-font-size\">Colocar un marco de unos 18 x 18 cm de base y 4 cm de alto sobre una bandeja con papel de hornear. Dosificar la masa dentro del marco.<\/p>\n\n\n\n<p class=\"has-small-font-size\">Colocar la rodaja de calabaza en el centro de la masa y cocer durante 35 minutos a 170 \u00baC en un horno est\u00e1tico o a 150 \u00baC en un horno ventilado.<\/p>\n<\/div>\n<\/div>\n\n\n\n<p>Si te has quedado con ganas de m\u00e1s, recuerda que nuestro nuevo libro <a href=\"https:\/\/jordibordas.com\/fr\/s\/producto\/libro-pasteleria-mas-saludable-ligera-y-sabrosa\/\"><strong>Pasteler\u00eda m\u00e1s saludable, ligera y sabrosa<\/strong><\/a> ya est\u00e1 a la venta. Con \u00e9l, aprender\u00e1s a elaborar desde desayunos y meriendas hasta tartas con diferentes texturas, pasando por postres, tartaletas y cakes de viaje. <\/p>\n\n\n\n<p>Se trata de un libro ideal para todas aquellas personas aficionadas a la pasteler\u00eda, as\u00ed como para aquellas que trabajan profesionalmente en el sector, pero desean descubrir una visi\u00f3n diferente del recetario tradicional.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfTe han sobrado calabazas de Halloween y no sabes qu\u00e9 hacer con ellas? Te proponemos este Pumpkin Cake s\u00faper jugoso y arom\u00e1tico para que aproveches este fant\u00e1stico fruto de temporada. Se trata de una elaboraci\u00f3n sin gluten y 100% vegana, y los ingredientes son muy f\u00e1ciles de conseguir: calabaza, nueces de pecan, aceite de oliva, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":6211,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[7],"tags":[25,62,80],"class_list":["post-6210","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-recetas","tag-ingredientes-de-pasteleria","tag-recetas-de-pasteleria","tag-recetas-veganas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Receta de Pumpkin Cake vegano y sin gluten - Jordi Bordas \u00c9cole de P\u00e2tisserie<\/title>\n<meta name=\"description\" content=\"\u00bfTe han sobrado calabazas de Halloween y no sabes qu\u00e9 hacer con ellas? Te proponemos este Pumpkin Cake s\u00faper jugoso y arom\u00e1tico.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jordibordas.com\/fr\/blog\/receta-de-pumkin-cake-vegano-y-sin-gluten\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Receta de Pumpkin Cake vegano y sin gluten - Jordi Bordas \u00c9cole de P\u00e2tisserie\" \/>\n<meta property=\"og:description\" content=\"\u00bfTe han sobrado calabazas de Halloween y no sabes qu\u00e9 hacer con ellas? Te proponemos este Pumpkin Cake s\u00faper jugoso y arom\u00e1tico.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jordibordas.com\/fr\/blog\/receta-de-pumkin-cake-vegano-y-sin-gluten\/\" \/>\n<meta property=\"og:site_name\" content=\"Jordi Bordas \u00c9cole de P\u00e2tisserie\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-05T11:39:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-14T07:30:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2021\/11\/Cake-de-calabaza.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"876\" \/>\n\t<meta property=\"og:image:height\" content=\"506\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marta\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marta\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/blog\\\/receta-de-pumkin-cake-vegano-y-sin-gluten\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/blog\\\/receta-de-pumkin-cake-vegano-y-sin-gluten\\\/\"},\"author\":{\"name\":\"Marta\",\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/#\\\/schema\\\/person\\\/ab762e8d24eeb55f78f4a4831dfa29fe\"},\"headline\":\"Receta de Pumpkin Cake vegano y sin gluten\",\"datePublished\":\"2021-11-05T11:39:47+00:00\",\"dateModified\":\"2022-09-14T07:30:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/blog\\\/receta-de-pumkin-cake-vegano-y-sin-gluten\\\/\"},\"wordCount\":474,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/blog\\\/receta-de-pumkin-cake-vegano-y-sin-gluten\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2021\\\/11\\\/Cake-de-calabaza.jpg\",\"keywords\":[\"INGREDIENTES DE PASTELER\u00cdA\",\"RECETAS DE PASTELER\u00cdA\",\"RECETAS VEGANAS\"],\"articleSection\":[\"Recetas\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jordibordas.com\\\/fr\\\/blog\\\/receta-de-pumkin-cake-vegano-y-sin-gluten\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/blog\\\/receta-de-pumkin-cake-vegano-y-sin-gluten\\\/\",\"url\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/blog\\\/receta-de-pumkin-cake-vegano-y-sin-gluten\\\/\",\"name\":\"Receta de Pumpkin Cake vegano y sin gluten - Jordi Bordas \u00c9cole de P\u00e2tisserie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/blog\\\/receta-de-pumkin-cake-vegano-y-sin-gluten\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/blog\\\/receta-de-pumkin-cake-vegano-y-sin-gluten\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2021\\\/11\\\/Cake-de-calabaza.jpg\",\"datePublished\":\"2021-11-05T11:39:47+00:00\",\"dateModified\":\"2022-09-14T07:30:29+00:00\",\"description\":\"\u00bfTe han sobrado calabazas de Halloween y no sabes qu\u00e9 hacer con ellas? Te proponemos este Pumpkin Cake s\u00faper jugoso y arom\u00e1tico.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/blog\\\/receta-de-pumkin-cake-vegano-y-sin-gluten\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jordibordas.com\\\/fr\\\/blog\\\/receta-de-pumkin-cake-vegano-y-sin-gluten\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/blog\\\/receta-de-pumkin-cake-vegano-y-sin-gluten\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2021\\\/11\\\/Cake-de-calabaza.jpg\",\"contentUrl\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2021\\\/11\\\/Cake-de-calabaza.jpg\",\"width\":876,\"height\":506,\"caption\":\"Cake de calabaza - Pumpkin Cake\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/blog\\\/receta-de-pumkin-cake-vegano-y-sin-gluten\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Receta de Pumpkin Cake vegano y sin gluten\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/\",\"name\":\"Jordi Bordas \u00c9cole de P\u00e2tisserie\",\"description\":\"Innovative Pastry Education\",\"publisher\":{\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/#organization\",\"name\":\"Jordi Bordas\",\"url\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2020\\\/11\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2020\\\/11\\\/logo.svg\",\"width\":274,\"height\":68,\"caption\":\"Jordi Bordas\"},\"image\":{\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/#\\\/schema\\\/person\\\/ab762e8d24eeb55f78f4a4831dfa29fe\",\"name\":\"Marta\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e681e4aec92ef304d8f3984d242a11654fb14cf41d5d9a672d7d6ff9b7be0d54?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e681e4aec92ef304d8f3984d242a11654fb14cf41d5d9a672d7d6ff9b7be0d54?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e681e4aec92ef304d8f3984d242a11654fb14cf41d5d9a672d7d6ff9b7be0d54?s=96&d=mm&r=g\",\"caption\":\"Marta\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Receta de Pumpkin Cake vegano y sin gluten - Jordi Bordas \u00c9cole de P\u00e2tisserie","description":"\u00bfTe han sobrado calabazas de Halloween y no sabes qu\u00e9 hacer con ellas? Te proponemos este Pumpkin Cake s\u00faper jugoso y arom\u00e1tico.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jordibordas.com\/fr\/blog\/receta-de-pumkin-cake-vegano-y-sin-gluten\/","og_locale":"fr_FR","og_type":"article","og_title":"Receta de Pumpkin Cake vegano y sin gluten - Jordi Bordas \u00c9cole de P\u00e2tisserie","og_description":"\u00bfTe han sobrado calabazas de Halloween y no sabes qu\u00e9 hacer con ellas? Te proponemos este Pumpkin Cake s\u00faper jugoso y arom\u00e1tico.","og_url":"https:\/\/jordibordas.com\/fr\/blog\/receta-de-pumkin-cake-vegano-y-sin-gluten\/","og_site_name":"Jordi Bordas \u00c9cole de P\u00e2tisserie","article_published_time":"2021-11-05T11:39:47+00:00","article_modified_time":"2022-09-14T07:30:29+00:00","og_image":[{"width":876,"height":506,"url":"https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2021\/11\/Cake-de-calabaza.jpg","type":"image\/jpeg"}],"author":"Marta","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Marta"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jordibordas.com\/fr\/blog\/receta-de-pumkin-cake-vegano-y-sin-gluten\/#article","isPartOf":{"@id":"https:\/\/jordibordas.com\/fr\/blog\/receta-de-pumkin-cake-vegano-y-sin-gluten\/"},"author":{"name":"Marta","@id":"https:\/\/jordibordas.com\/fr\/#\/schema\/person\/ab762e8d24eeb55f78f4a4831dfa29fe"},"headline":"Receta de Pumpkin Cake vegano y sin gluten","datePublished":"2021-11-05T11:39:47+00:00","dateModified":"2022-09-14T07:30:29+00:00","mainEntityOfPage":{"@id":"https:\/\/jordibordas.com\/fr\/blog\/receta-de-pumkin-cake-vegano-y-sin-gluten\/"},"wordCount":474,"commentCount":0,"publisher":{"@id":"https:\/\/jordibordas.com\/fr\/#organization"},"image":{"@id":"https:\/\/jordibordas.com\/fr\/blog\/receta-de-pumkin-cake-vegano-y-sin-gluten\/#primaryimage"},"thumbnailUrl":"https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2021\/11\/Cake-de-calabaza.jpg","keywords":["INGREDIENTES DE PASTELER\u00cdA","RECETAS DE PASTELER\u00cdA","RECETAS VEGANAS"],"articleSection":["Recetas"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jordibordas.com\/fr\/blog\/receta-de-pumkin-cake-vegano-y-sin-gluten\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jordibordas.com\/fr\/blog\/receta-de-pumkin-cake-vegano-y-sin-gluten\/","url":"https:\/\/jordibordas.com\/fr\/blog\/receta-de-pumkin-cake-vegano-y-sin-gluten\/","name":"Receta de Pumpkin Cake vegano y sin gluten - Jordi Bordas \u00c9cole de P\u00e2tisserie","isPartOf":{"@id":"https:\/\/jordibordas.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jordibordas.com\/fr\/blog\/receta-de-pumkin-cake-vegano-y-sin-gluten\/#primaryimage"},"image":{"@id":"https:\/\/jordibordas.com\/fr\/blog\/receta-de-pumkin-cake-vegano-y-sin-gluten\/#primaryimage"},"thumbnailUrl":"https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2021\/11\/Cake-de-calabaza.jpg","datePublished":"2021-11-05T11:39:47+00:00","dateModified":"2022-09-14T07:30:29+00:00","description":"\u00bfTe han sobrado calabazas de Halloween y no sabes qu\u00e9 hacer con ellas? Te proponemos este Pumpkin Cake s\u00faper jugoso y arom\u00e1tico.","breadcrumb":{"@id":"https:\/\/jordibordas.com\/fr\/blog\/receta-de-pumkin-cake-vegano-y-sin-gluten\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jordibordas.com\/fr\/blog\/receta-de-pumkin-cake-vegano-y-sin-gluten\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/jordibordas.com\/fr\/blog\/receta-de-pumkin-cake-vegano-y-sin-gluten\/#primaryimage","url":"https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2021\/11\/Cake-de-calabaza.jpg","contentUrl":"https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2021\/11\/Cake-de-calabaza.jpg","width":876,"height":506,"caption":"Cake de calabaza - Pumpkin Cake"},{"@type":"BreadcrumbList","@id":"https:\/\/jordibordas.com\/fr\/blog\/receta-de-pumkin-cake-vegano-y-sin-gluten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/jordibordas.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Receta de Pumpkin Cake vegano y sin gluten"}]},{"@type":"WebSite","@id":"https:\/\/jordibordas.com\/fr\/#website","url":"https:\/\/jordibordas.com\/fr\/","name":"Jordi Bordas \u00c9cole de P\u00e2tisserie","description":"Innovative Pastry Education","publisher":{"@id":"https:\/\/jordibordas.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jordibordas.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/jordibordas.com\/fr\/#organization","name":"Jordi Bordas","url":"https:\/\/jordibordas.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/jordibordas.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2020\/11\/logo.svg","contentUrl":"https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2020\/11\/logo.svg","width":274,"height":68,"caption":"Jordi Bordas"},"image":{"@id":"https:\/\/jordibordas.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/jordibordas.com\/fr\/#\/schema\/person\/ab762e8d24eeb55f78f4a4831dfa29fe","name":"Marta","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/e681e4aec92ef304d8f3984d242a11654fb14cf41d5d9a672d7d6ff9b7be0d54?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e681e4aec92ef304d8f3984d242a11654fb14cf41d5d9a672d7d6ff9b7be0d54?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e681e4aec92ef304d8f3984d242a11654fb14cf41d5d9a672d7d6ff9b7be0d54?s=96&d=mm&r=g","caption":"Marta"}}]}},"_links":{"self":[{"href":"https:\/\/jordibordas.com\/fr\/wp-json\/wp\/v2\/posts\/6210","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jordibordas.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jordibordas.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jordibordas.com\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/jordibordas.com\/fr\/wp-json\/wp\/v2\/comments?post=6210"}],"version-history":[{"count":7,"href":"https:\/\/jordibordas.com\/fr\/wp-json\/wp\/v2\/posts\/6210\/revisions"}],"predecessor-version":[{"id":12331,"href":"https:\/\/jordibordas.com\/fr\/wp-json\/wp\/v2\/posts\/6210\/revisions\/12331"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jordibordas.com\/fr\/wp-json\/wp\/v2\/media\/6211"}],"wp:attachment":[{"href":"https:\/\/jordibordas.com\/fr\/wp-json\/wp\/v2\/media?parent=6210"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jordibordas.com\/fr\/wp-json\/wp\/v2\/categories?post=6210"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jordibordas.com\/fr\/wp-json\/wp\/v2\/tags?post=6210"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}