{"id":9646,"date":"2022-06-30T13:01:17","date_gmt":"2022-06-30T11:01:17","guid":{"rendered":"https:\/\/jordibordas.com\/fr\/?p=9646"},"modified":"2022-12-05T10:59:09","modified_gmt":"2022-12-05T09:59:09","slug":"que-necesitas-saber-antes-de-empezar-una-receta-del-libro","status":"publish","type":"post","link":"https:\/\/jordibordas.com\/fr\/blog\/que-necesitas-saber-antes-de-empezar-una-receta-del-libro\/","title":{"rendered":"\u00bfQu\u00e9 necesitas saber antes de empezar una receta del libro?"},"content":{"rendered":"\n<p>\u00bfPreparado para elaborar las recetas de nuestro libro\u00a0<a href=\"https:\/\/jordibordas.com\/fr\/s\/producto\/libro-pasteleria-mas-saludable-ligera-y-sabrosa\/\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u201cPasteler\u00eda m\u00e1s saludable, ligera y sabrosa\u201d<\/a>? Han sido cuidadosamente escritas y revisadas para que se puedan realizar desde casa con \u00e9xito, pero, antes de empezar, te dejamos con una serie de recomendaciones y advertencias que te ayudar\u00e1n a conseguir un \u00f3ptimo resultado en todas ellas.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Presencia de al\u00e9rgenos<\/h3>\n\n\n\n<p>Hemos incorporado dos p\u00e1ginas donde se especifica si las elaboraciones son libres o no de los al\u00e9rgenos m\u00e1s comunes en pasteler\u00eda (gluten, lactosa, soja, huevo, frutos secos\u2026). Son perfectas para que las personas con alguna alergia o intolerancia alimentaria puedan consultarlas. Por ejemplo, 40 de 44 recetas del libro son sin lactosa. \ud83e\udd5b<\/p>\n\n\n\n<div style=\"height:26px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button aligncenter has-custom-width wp-block-button__width-100 has-custom-font-size has-small-font-size\"><a class=\"wp-block-button__link has-white-color has-text-color has-background\" href=\"https:\/\/www.jordibordas.com\/fr\/tienda\/wp-content\/uploads\/sites\/6\/sites\/3\/2021\/10\/Alergenos-y-distintivos-Pasteleria-saludable-ligera-y-sabrosa.pdf\" style=\"border-radius:0px;background-color:#d5a678\">Descarga la tabla de al\u00e9rgenos y distintivos de dietas especiales<\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Leer la receta y fijarnos en su dificultad<\/h3>\n\n\n\n<p>Antes de empezar a elaborar una receta es necesario leerla de principio a fin, para asegurar que se disponen de todos los ingredientes y utensilios necesarios y de que se entienden todos los pasos del proceso.<\/p>\n\n\n\n<p>En todas las recetas indicamos si el nivel de dificultad es bajo, medio o alto. Aunque todas las elaboraciones est\u00e1n pensadas para realizar en casa, algunas de ellas son m\u00e1s laboriosas, o bien, alguna parte de su proceso requiere m\u00e1s precisi\u00f3n.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Pesar y preparar los ingredientes<\/h3>\n\n\n\n<p>Debemos pesar todos los ingredientes antes de empezar. Aquellos que se puedan secar (como la yema del huevo) o los que se apelmacen con la humedad, deber\u00e1n cubrirse con film transparente hasta su uso.<\/p>\n\n\n\n<p>Por otro lado, algunos ingredientes van acompa\u00f1ados de una acotaci\u00f3n que indica en qu\u00e9 estado o a qu\u00e9 temperatura han de usarse. Estas preparaciones han de realizarse antes de comenzar a elaborar la receta. Las temperaturas indicadas son las que deben tener los ingredientes en el momento de usarlos, por lo que habr\u00e1 que volver a comprobar su temperatura antes de usarlos.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">\u00a1Las temperaturas son importantes!<\/h3>\n\n\n\n<p>Algunos ingredientes como la cobertura de chocolate se queman o se cuajan con facilidad y hay que calentarlos con mucho cuidado. El mejor m\u00e9todo para hacerlo es el ba\u00f1o mar\u00eda, removiendo para distribuir uniformemente el calor.<\/p>\n\n\n\n<p>Tambi\u00e9n es importante respetar las temperaturas a las que se enfr\u00edan o calientan las preparaciones durante el proceso de elaboraci\u00f3n.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Precalentar el horno<\/h3>\n\n\n\n<p>Es necesario encender el horno con anterioridad para que al introducir la preparaci\u00f3n ya est\u00e9 a la temperatura indicada. Si no lo hacemos as\u00ed, durante gran parte de la cocci\u00f3n, la temperatura no ser\u00e1 la correcta.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Congelaci\u00f3n y descongelaci\u00f3n<\/h3>\n\n\n\n<p>En cada elaboraci\u00f3n se detalla si el producto se puede congelar. Para conservar correctamente las elaboraciones congeladas es necesario aislarlas de la atm\u00f3sfera mediante envases o bolsas herm\u00e9ticas. As\u00ed evitaremos que el producto absorba olores indeseados o que se condense el agua durante la descongelaci\u00f3n.<\/p>\n\n\n\n<p>El tiempo de descongelaci\u00f3n variar\u00e1 seg\u00fan el volumen y la composici\u00f3n de la receta, pero puede ir de 1 a 8 horas. Cuando la receta lo especifique, es importante asegurarse de que las elaboraciones est\u00e9n completamente congeladas antes de manipularlas.<\/p>\n\n\n\n<p>Con este libro de recetas de Jordi Bordas aprender\u00e1s a elaborar una colecci\u00f3n de productos de pasteler\u00eda m\u00e1s saludables, ligeros y sabrosos; desde desayunos y meriendas hasta tartas con diferentes texturas, pasando por postres, tartaletas y cakes de viaje.<\/p>\n\n\n\n<p>Y, si te quedas con ganas de m\u00e1s, recuerda que en el&nbsp;<a href=\"https:\/\/www.jordibordas.com\/fr\/curso-online-de-pasteleria-bconcept\/\">Curso de Pasteler\u00eda B\u00b7Concept online y extendido&nbsp;<\/a>tratamos en profundidad todos los conceptos te\u00f3ricos del libro e ingredientes. \u00bfQuieres seguir aprendiendo junto a nosotros?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfPreparado para elaborar las recetas de nuestro libro\u00a0\u201cPasteler\u00eda m\u00e1s saludable, ligera y sabrosa\u201d? Han sido cuidadosamente escritas y revisadas para que se puedan realizar desde casa con \u00e9xito, pero, antes de empezar, te dejamos con una serie de recomendaciones y advertencias que te ayudar\u00e1n a conseguir un \u00f3ptimo resultado en todas ellas. Presencia de al\u00e9rgenos [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":9647,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[5,7],"tags":[25,72,62,79,71],"class_list":["post-9646","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-b-concept","category-recetas","tag-ingredientes-de-pasteleria","tag-libros-de-pasteleria","tag-recetas-de-pasteleria","tag-recetas-sin-gluten","tag-tecnicas-de-pasteleria"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfQu\u00e9 necesitas saber antes de empezar una receta del libro? - Jordi Bordas \u00c9cole de P\u00e2tisserie<\/title>\n<meta name=\"description\" content=\"\u00bfPreparado para elaborar las recetas de nuestro libro \u201cPasteler\u00eda m\u00e1s saludable, ligera y sabrosa\u201d?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jordibordas.com\/fr\/blog\/que-necesitas-saber-antes-de-empezar-una-receta-del-libro\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQu\u00e9 necesitas saber antes de empezar una receta del libro? - Jordi Bordas \u00c9cole de P\u00e2tisserie\" \/>\n<meta property=\"og:description\" content=\"\u00bfPreparado para elaborar las recetas de nuestro libro \u201cPasteler\u00eda m\u00e1s saludable, ligera y sabrosa\u201d?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jordibordas.com\/fr\/blog\/que-necesitas-saber-antes-de-empezar-una-receta-del-libro\/\" \/>\n<meta property=\"og:site_name\" content=\"Jordi Bordas \u00c9cole de P\u00e2tisserie\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-30T11:01:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-05T09:59:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/06\/recetas-libro.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"876\" \/>\n\t<meta property=\"og:image:height\" content=\"506\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jordi Bordas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jordi Bordas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/blog\\\/que-necesitas-saber-antes-de-empezar-una-receta-del-libro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/blog\\\/que-necesitas-saber-antes-de-empezar-una-receta-del-libro\\\/\"},\"author\":{\"name\":\"Jordi Bordas\",\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/#\\\/schema\\\/person\\\/946e8de6b1aa472478dca1163ee12ad3\"},\"headline\":\"\u00bfQu\u00e9 necesitas saber antes de empezar una receta del libro?\",\"datePublished\":\"2022-06-30T11:01:17+00:00\",\"dateModified\":\"2022-12-05T09:59:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/blog\\\/que-necesitas-saber-antes-de-empezar-una-receta-del-libro\\\/\"},\"wordCount\":616,\"publisher\":{\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/blog\\\/que-necesitas-saber-antes-de-empezar-una-receta-del-libro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/06\\\/recetas-libro.jpg\",\"keywords\":[\"INGREDIENTES DE PASTELER\u00cdA\",\"LIBROS DE PASTELER\u00cdA\",\"RECETAS DE PASTELER\u00cdA\",\"RECETAS SIN GLUTEN\",\"T\u00c9CNICAS DE PASTELER\u00cdA\"],\"articleSection\":[\"B\u00b7Concept\",\"Recetas\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/blog\\\/que-necesitas-saber-antes-de-empezar-una-receta-del-libro\\\/\",\"url\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/blog\\\/que-necesitas-saber-antes-de-empezar-una-receta-del-libro\\\/\",\"name\":\"\u00bfQu\u00e9 necesitas saber antes de empezar una receta del libro? - Jordi Bordas \u00c9cole de P\u00e2tisserie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/blog\\\/que-necesitas-saber-antes-de-empezar-una-receta-del-libro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/blog\\\/que-necesitas-saber-antes-de-empezar-una-receta-del-libro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/06\\\/recetas-libro.jpg\",\"datePublished\":\"2022-06-30T11:01:17+00:00\",\"dateModified\":\"2022-12-05T09:59:09+00:00\",\"description\":\"\u00bfPreparado para elaborar las recetas de nuestro libro \u201cPasteler\u00eda m\u00e1s saludable, ligera y sabrosa\u201d?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/blog\\\/que-necesitas-saber-antes-de-empezar-una-receta-del-libro\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jordibordas.com\\\/fr\\\/blog\\\/que-necesitas-saber-antes-de-empezar-una-receta-del-libro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/blog\\\/que-necesitas-saber-antes-de-empezar-una-receta-del-libro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/06\\\/recetas-libro.jpg\",\"contentUrl\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/06\\\/recetas-libro.jpg\",\"width\":876,\"height\":506},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/blog\\\/que-necesitas-saber-antes-de-empezar-una-receta-del-libro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfQu\u00e9 necesitas saber antes de empezar una receta del libro?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/\",\"name\":\"Jordi Bordas \u00c9cole de P\u00e2tisserie\",\"description\":\"Innovative Pastry Education\",\"publisher\":{\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/#organization\",\"name\":\"Jordi Bordas\",\"url\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2020\\\/11\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2020\\\/11\\\/logo.svg\",\"width\":274,\"height\":68,\"caption\":\"Jordi Bordas\"},\"image\":{\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jordibordas.com\\\/fr\\\/#\\\/schema\\\/person\\\/946e8de6b1aa472478dca1163ee12ad3\",\"name\":\"Jordi Bordas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e820efd5d2dd738b3ab18409afa9d6db7be86553a9894b9dc78088b6998e2f77?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e820efd5d2dd738b3ab18409afa9d6db7be86553a9894b9dc78088b6998e2f77?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e820efd5d2dd738b3ab18409afa9d6db7be86553a9894b9dc78088b6998e2f77?s=96&d=mm&r=g\",\"caption\":\"Jordi Bordas\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQu\u00e9 necesitas saber antes de empezar una receta del libro? - Jordi Bordas \u00c9cole de P\u00e2tisserie","description":"\u00bfPreparado para elaborar las recetas de nuestro libro \u201cPasteler\u00eda m\u00e1s saludable, ligera y sabrosa\u201d?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jordibordas.com\/fr\/blog\/que-necesitas-saber-antes-de-empezar-una-receta-del-libro\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00bfQu\u00e9 necesitas saber antes de empezar una receta del libro? - Jordi Bordas \u00c9cole de P\u00e2tisserie","og_description":"\u00bfPreparado para elaborar las recetas de nuestro libro \u201cPasteler\u00eda m\u00e1s saludable, ligera y sabrosa\u201d?","og_url":"https:\/\/jordibordas.com\/fr\/blog\/que-necesitas-saber-antes-de-empezar-una-receta-del-libro\/","og_site_name":"Jordi Bordas \u00c9cole de P\u00e2tisserie","article_published_time":"2022-06-30T11:01:17+00:00","article_modified_time":"2022-12-05T09:59:09+00:00","og_image":[{"width":876,"height":506,"url":"https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/06\/recetas-libro.jpg","type":"image\/jpeg"}],"author":"Jordi Bordas","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Jordi Bordas","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jordibordas.com\/fr\/blog\/que-necesitas-saber-antes-de-empezar-una-receta-del-libro\/#article","isPartOf":{"@id":"https:\/\/jordibordas.com\/fr\/blog\/que-necesitas-saber-antes-de-empezar-una-receta-del-libro\/"},"author":{"name":"Jordi Bordas","@id":"https:\/\/jordibordas.com\/fr\/#\/schema\/person\/946e8de6b1aa472478dca1163ee12ad3"},"headline":"\u00bfQu\u00e9 necesitas saber antes de empezar una receta del libro?","datePublished":"2022-06-30T11:01:17+00:00","dateModified":"2022-12-05T09:59:09+00:00","mainEntityOfPage":{"@id":"https:\/\/jordibordas.com\/fr\/blog\/que-necesitas-saber-antes-de-empezar-una-receta-del-libro\/"},"wordCount":616,"publisher":{"@id":"https:\/\/jordibordas.com\/fr\/#organization"},"image":{"@id":"https:\/\/jordibordas.com\/fr\/blog\/que-necesitas-saber-antes-de-empezar-una-receta-del-libro\/#primaryimage"},"thumbnailUrl":"https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/06\/recetas-libro.jpg","keywords":["INGREDIENTES DE PASTELER\u00cdA","LIBROS DE PASTELER\u00cdA","RECETAS DE PASTELER\u00cdA","RECETAS SIN GLUTEN","T\u00c9CNICAS DE PASTELER\u00cdA"],"articleSection":["B\u00b7Concept","Recetas"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/jordibordas.com\/fr\/blog\/que-necesitas-saber-antes-de-empezar-una-receta-del-libro\/","url":"https:\/\/jordibordas.com\/fr\/blog\/que-necesitas-saber-antes-de-empezar-una-receta-del-libro\/","name":"\u00bfQu\u00e9 necesitas saber antes de empezar una receta del libro? - Jordi Bordas \u00c9cole de P\u00e2tisserie","isPartOf":{"@id":"https:\/\/jordibordas.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jordibordas.com\/fr\/blog\/que-necesitas-saber-antes-de-empezar-una-receta-del-libro\/#primaryimage"},"image":{"@id":"https:\/\/jordibordas.com\/fr\/blog\/que-necesitas-saber-antes-de-empezar-una-receta-del-libro\/#primaryimage"},"thumbnailUrl":"https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/06\/recetas-libro.jpg","datePublished":"2022-06-30T11:01:17+00:00","dateModified":"2022-12-05T09:59:09+00:00","description":"\u00bfPreparado para elaborar las recetas de nuestro libro \u201cPasteler\u00eda m\u00e1s saludable, ligera y sabrosa\u201d?","breadcrumb":{"@id":"https:\/\/jordibordas.com\/fr\/blog\/que-necesitas-saber-antes-de-empezar-una-receta-del-libro\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jordibordas.com\/fr\/blog\/que-necesitas-saber-antes-de-empezar-una-receta-del-libro\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/jordibordas.com\/fr\/blog\/que-necesitas-saber-antes-de-empezar-una-receta-del-libro\/#primaryimage","url":"https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/06\/recetas-libro.jpg","contentUrl":"https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2022\/06\/recetas-libro.jpg","width":876,"height":506},{"@type":"BreadcrumbList","@id":"https:\/\/jordibordas.com\/fr\/blog\/que-necesitas-saber-antes-de-empezar-una-receta-del-libro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/jordibordas.com\/fr\/"},{"@type":"ListItem","position":2,"name":"\u00bfQu\u00e9 necesitas saber antes de empezar una receta del libro?"}]},{"@type":"WebSite","@id":"https:\/\/jordibordas.com\/fr\/#website","url":"https:\/\/jordibordas.com\/fr\/","name":"Jordi Bordas \u00c9cole de P\u00e2tisserie","description":"Innovative Pastry Education","publisher":{"@id":"https:\/\/jordibordas.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jordibordas.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/jordibordas.com\/fr\/#organization","name":"Jordi Bordas","url":"https:\/\/jordibordas.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/jordibordas.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2020\/11\/logo.svg","contentUrl":"https:\/\/jordibordas.com\/fr\/wp-content\/uploads\/sites\/6\/2020\/11\/logo.svg","width":274,"height":68,"caption":"Jordi Bordas"},"image":{"@id":"https:\/\/jordibordas.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/jordibordas.com\/fr\/#\/schema\/person\/946e8de6b1aa472478dca1163ee12ad3","name":"Jordi Bordas","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/e820efd5d2dd738b3ab18409afa9d6db7be86553a9894b9dc78088b6998e2f77?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e820efd5d2dd738b3ab18409afa9d6db7be86553a9894b9dc78088b6998e2f77?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e820efd5d2dd738b3ab18409afa9d6db7be86553a9894b9dc78088b6998e2f77?s=96&d=mm&r=g","caption":"Jordi Bordas"}}]}},"_links":{"self":[{"href":"https:\/\/jordibordas.com\/fr\/wp-json\/wp\/v2\/posts\/9646","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jordibordas.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jordibordas.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jordibordas.com\/fr\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/jordibordas.com\/fr\/wp-json\/wp\/v2\/comments?post=9646"}],"version-history":[{"count":9,"href":"https:\/\/jordibordas.com\/fr\/wp-json\/wp\/v2\/posts\/9646\/revisions"}],"predecessor-version":[{"id":10666,"href":"https:\/\/jordibordas.com\/fr\/wp-json\/wp\/v2\/posts\/9646\/revisions\/10666"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jordibordas.com\/fr\/wp-json\/wp\/v2\/media\/9647"}],"wp:attachment":[{"href":"https:\/\/jordibordas.com\/fr\/wp-json\/wp\/v2\/media?parent=9646"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jordibordas.com\/fr\/wp-json\/wp\/v2\/categories?post=9646"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jordibordas.com\/fr\/wp-json\/wp\/v2\/tags?post=9646"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}