{"id":10855,"date":"2025-03-13T10:35:37","date_gmt":"2025-03-13T09:35:37","guid":{"rendered":"https:\/\/jordibordas.com\/z\/?post_type=lesson&#038;p=10855"},"modified":"2025-03-24T14:31:21","modified_gmt":"2025-03-24T13:31:21","slug":"leccion-de-prueba-2","status":"publish","type":"lesson","link":"https:\/\/jordibordas.com\/z\/leccion\/leccion-de-prueba-2\/","title":{"rendered":"Lecci\u00f3n de prueba 2"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"_themeisle_gutenberg_block_has_review":false,"_initial_content":"","_new_post":false,"_quiz_has_questions":false,"_lesson_complexity":"easy","_lesson_length":10,"_lesson_course":10832,"_lesson_preview":""},"lesson-tag":[],"class_list":["post-10855","lesson","type-lesson","status-publish","post-password-required","hentry","module-modulo-de-prueba","post"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lecci\u00f3n de prueba 2 - Innovative Pastry Education<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lecci\u00f3n de prueba 2 - Innovative Pastry Education\" \/>\n<meta property=\"og:description\" content=\"No hay extracto porque es una entrada protegida.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jordibordas.com\/z\/leccion\/leccion-de-prueba-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Innovative Pastry Education\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-24T13:31:21+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jordibordas.com\\\/z\\\/leccion\\\/leccion-de-prueba-2\\\/\",\"url\":\"https:\\\/\\\/jordibordas.com\\\/z\\\/leccion\\\/leccion-de-prueba-2\\\/\",\"name\":\"Lecci\u00f3n de prueba 2 - Innovative Pastry Education\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jordibordas.com\\\/z\\\/#website\"},\"datePublished\":\"2025-03-13T09:35:37+00:00\",\"dateModified\":\"2025-03-24T13:31:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jordibordas.com\\\/z\\\/leccion\\\/leccion-de-prueba-2\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jordibordas.com\\\/z\\\/#website\",\"url\":\"https:\\\/\\\/jordibordas.com\\\/z\\\/\",\"name\":\"Innovative Pastry Education\",\"description\":\"Innovative Pastry Education\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jordibordas.com\\\/z\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lecci\u00f3n de prueba 2 - Innovative Pastry Education","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Lecci\u00f3n de prueba 2 - Innovative Pastry Education","og_description":"No hay extracto porque es una entrada protegida.","og_url":"https:\/\/jordibordas.com\/z\/leccion\/leccion-de-prueba-2\/","og_site_name":"Innovative Pastry Education","article_modified_time":"2025-03-24T13:31:21+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/jordibordas.com\/z\/leccion\/leccion-de-prueba-2\/","url":"https:\/\/jordibordas.com\/z\/leccion\/leccion-de-prueba-2\/","name":"Lecci\u00f3n de prueba 2 - Innovative Pastry Education","isPartOf":{"@id":"https:\/\/jordibordas.com\/z\/#website"},"datePublished":"2025-03-13T09:35:37+00:00","dateModified":"2025-03-24T13:31:21+00:00","breadcrumb":{"@id":"https:\/\/jordibordas.com\/z\/leccion\/leccion-de-prueba-2\/#breadcrumb"},"inLanguage":"es"},{"@type":"WebSite","@id":"https:\/\/jordibordas.com\/z\/#website","url":"https:\/\/jordibordas.com\/z\/","name":"Innovative Pastry Education","description":"Innovative Pastry Education","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jordibordas.com\/z\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"is_coteacher":false,"_links":{"self":[{"href":"https:\/\/jordibordas.com\/z\/wp-json\/wp\/v2\/lessons\/10855","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jordibordas.com\/z\/wp-json\/wp\/v2\/lessons"}],"about":[{"href":"https:\/\/jordibordas.com\/z\/wp-json\/wp\/v2\/types\/lesson"}],"version-history":[{"count":4,"href":"https:\/\/jordibordas.com\/z\/wp-json\/wp\/v2\/lessons\/10855\/revisions"}],"predecessor-version":[{"id":10892,"href":"https:\/\/jordibordas.com\/z\/wp-json\/wp\/v2\/lessons\/10855\/revisions\/10892"}],"wp:attachment":[{"href":"https:\/\/jordibordas.com\/z\/wp-json\/wp\/v2\/media?parent=10855"}],"wp:term":[{"taxonomy":"lesson-tag","embeddable":true,"href":"https:\/\/jordibordas.com\/z\/wp-json\/wp\/v2\/lesson-tag?post=10855"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}