{"id":9189,"date":"2024-04-18T17:09:42","date_gmt":"2024-04-18T15:09:42","guid":{"rendered":"https:\/\/jordibordas.com\/z\/?post_type=lesson&#038;p=9189"},"modified":"2024-04-25T16:11:47","modified_gmt":"2024-04-25T14:11:47","slug":"tarta-de-frambuesa-y-almendra-sinazucar","status":"publish","type":"lesson","link":"https:\/\/jordibordas.com\/z\/leccion\/tarta-de-frambuesa-y-almendra-sinazucar\/","title":{"rendered":"Tarta de frambuesa y almendra"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":9284,"template":"","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"_themeisle_gutenberg_block_has_review":false,"_initial_content":"","_new_post":false,"_quiz_has_questions":false,"_lesson_complexity":"","_lesson_length":29,"_lesson_course":9182,"_lesson_preview":""},"lesson-tag":[],"class_list":["post-9189","lesson","type-lesson","status-publish","post-password-required","hentry","module-elaboraciones-sinazucar","post"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tarta de frambuesa y almendra - Innovative Pastry Education<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tarta de frambuesa y almendra - Innovative Pastry Education\" \/>\n<meta property=\"og:description\" content=\"No hay extracto porque es una entrada protegida.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jordibordas.com\/z\/leccion\/tarta-de-frambuesa-y-almendra-sinazucar\/\" \/>\n<meta property=\"og:site_name\" content=\"Innovative Pastry Education\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-25T14:11:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jordibordas.com\\\/z\\\/leccion\\\/tarta-de-frambuesa-y-almendra-sinazucar\\\/\",\"url\":\"https:\\\/\\\/jordibordas.com\\\/z\\\/leccion\\\/tarta-de-frambuesa-y-almendra-sinazucar\\\/\",\"name\":\"Tarta de frambuesa y almendra - Innovative Pastry Education\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jordibordas.com\\\/z\\\/#website\"},\"datePublished\":\"2024-04-18T15:09:42+00:00\",\"dateModified\":\"2024-04-25T14:11:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jordibordas.com\\\/z\\\/leccion\\\/tarta-de-frambuesa-y-almendra-sinazucar\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jordibordas.com\\\/z\\\/#website\",\"url\":\"https:\\\/\\\/jordibordas.com\\\/z\\\/\",\"name\":\"Innovative Pastry Education\",\"description\":\"Innovative Pastry Education\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jordibordas.com\\\/z\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tarta de frambuesa y almendra - Innovative Pastry Education","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Tarta de frambuesa y almendra - Innovative Pastry Education","og_description":"No hay extracto porque es una entrada protegida.","og_url":"https:\/\/jordibordas.com\/z\/leccion\/tarta-de-frambuesa-y-almendra-sinazucar\/","og_site_name":"Innovative Pastry Education","article_modified_time":"2024-04-25T14:11:47+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/jordibordas.com\/z\/leccion\/tarta-de-frambuesa-y-almendra-sinazucar\/","url":"https:\/\/jordibordas.com\/z\/leccion\/tarta-de-frambuesa-y-almendra-sinazucar\/","name":"Tarta de frambuesa y almendra - Innovative Pastry Education","isPartOf":{"@id":"https:\/\/jordibordas.com\/z\/#website"},"datePublished":"2024-04-18T15:09:42+00:00","dateModified":"2024-04-25T14:11:47+00:00","breadcrumb":{"@id":"https:\/\/jordibordas.com\/z\/leccion\/tarta-de-frambuesa-y-almendra-sinazucar\/#breadcrumb"},"inLanguage":"es"},{"@type":"WebSite","@id":"https:\/\/jordibordas.com\/z\/#website","url":"https:\/\/jordibordas.com\/z\/","name":"Innovative Pastry Education","description":"Innovative Pastry Education","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jordibordas.com\/z\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"is_coteacher":false,"_links":{"self":[{"href":"https:\/\/jordibordas.com\/z\/wp-json\/wp\/v2\/lessons\/9189","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jordibordas.com\/z\/wp-json\/wp\/v2\/lessons"}],"about":[{"href":"https:\/\/jordibordas.com\/z\/wp-json\/wp\/v2\/types\/lesson"}],"version-history":[{"count":4,"href":"https:\/\/jordibordas.com\/z\/wp-json\/wp\/v2\/lessons\/9189\/revisions"}],"predecessor-version":[{"id":9277,"href":"https:\/\/jordibordas.com\/z\/wp-json\/wp\/v2\/lessons\/9189\/revisions\/9277"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jordibordas.com\/z\/wp-json\/wp\/v2\/media\/9284"}],"wp:attachment":[{"href":"https:\/\/jordibordas.com\/z\/wp-json\/wp\/v2\/media?parent=9189"}],"wp:term":[{"taxonomy":"lesson-tag","embeddable":true,"href":"https:\/\/jordibordas.com\/z\/wp-json\/wp\/v2\/lesson-tag?post=9189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}