{"id":9551,"date":"2024-05-13T12:23:12","date_gmt":"2024-05-13T10:23:12","guid":{"rendered":"https:\/\/jordibordas.com\/z\/?post_type=lesson&#038;p=9551"},"modified":"2024-06-19T12:11:57","modified_gmt":"2024-06-19T10:11:57","slug":"foros-de-consulta-vgn","status":"publish","type":"lesson","link":"https:\/\/jordibordas.com\/z\/leccion\/foros-de-consulta-vgn\/","title":{"rendered":"Foros de consulta"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"_themeisle_gutenberg_block_has_review":false,"_initial_content":"","_new_post":false,"_quiz_has_questions":false,"_lesson_complexity":"","_lesson_length":0,"_lesson_course":7780,"_lesson_preview":""},"lesson-tag":[],"class_list":["post-9551","lesson","type-lesson","status-publish","post-password-required","hentry","module-bienvenida-vgn","post"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Foros de consulta - Innovative Pastry Education<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Foros de consulta - Innovative Pastry Education\" \/>\n<meta property=\"og:description\" content=\"No hay extracto porque es una entrada protegida.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jordibordas.com\/z\/leccion\/foros-de-consulta-vgn\/\" \/>\n<meta property=\"og:site_name\" content=\"Innovative Pastry Education\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-19T10:11:57+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jordibordas.com\\\/z\\\/leccion\\\/foros-de-consulta-vgn\\\/\",\"url\":\"https:\\\/\\\/jordibordas.com\\\/z\\\/leccion\\\/foros-de-consulta-vgn\\\/\",\"name\":\"Foros de consulta - Innovative Pastry Education\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jordibordas.com\\\/z\\\/#website\"},\"datePublished\":\"2024-05-13T10:23:12+00:00\",\"dateModified\":\"2024-06-19T10:11:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jordibordas.com\\\/z\\\/leccion\\\/foros-de-consulta-vgn\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jordibordas.com\\\/z\\\/#website\",\"url\":\"https:\\\/\\\/jordibordas.com\\\/z\\\/\",\"name\":\"Innovative Pastry Education\",\"description\":\"Innovative Pastry Education\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jordibordas.com\\\/z\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Foros de consulta - Innovative Pastry Education","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Foros de consulta - Innovative Pastry Education","og_description":"No hay extracto porque es una entrada protegida.","og_url":"https:\/\/jordibordas.com\/z\/leccion\/foros-de-consulta-vgn\/","og_site_name":"Innovative Pastry Education","article_modified_time":"2024-06-19T10:11:57+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/jordibordas.com\/z\/leccion\/foros-de-consulta-vgn\/","url":"https:\/\/jordibordas.com\/z\/leccion\/foros-de-consulta-vgn\/","name":"Foros de consulta - Innovative Pastry Education","isPartOf":{"@id":"https:\/\/jordibordas.com\/z\/#website"},"datePublished":"2024-05-13T10:23:12+00:00","dateModified":"2024-06-19T10:11:57+00:00","breadcrumb":{"@id":"https:\/\/jordibordas.com\/z\/leccion\/foros-de-consulta-vgn\/#breadcrumb"},"inLanguage":"es"},{"@type":"WebSite","@id":"https:\/\/jordibordas.com\/z\/#website","url":"https:\/\/jordibordas.com\/z\/","name":"Innovative Pastry Education","description":"Innovative Pastry Education","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jordibordas.com\/z\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"is_coteacher":false,"_links":{"self":[{"href":"https:\/\/jordibordas.com\/z\/wp-json\/wp\/v2\/lessons\/9551","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jordibordas.com\/z\/wp-json\/wp\/v2\/lessons"}],"about":[{"href":"https:\/\/jordibordas.com\/z\/wp-json\/wp\/v2\/types\/lesson"}],"version-history":[{"count":2,"href":"https:\/\/jordibordas.com\/z\/wp-json\/wp\/v2\/lessons\/9551\/revisions"}],"predecessor-version":[{"id":9812,"href":"https:\/\/jordibordas.com\/z\/wp-json\/wp\/v2\/lessons\/9551\/revisions\/9812"}],"wp:attachment":[{"href":"https:\/\/jordibordas.com\/z\/wp-json\/wp\/v2\/media?parent=9551"}],"wp:term":[{"taxonomy":"lesson-tag","embeddable":true,"href":"https:\/\/jordibordas.com\/z\/wp-json\/wp\/v2\/lesson-tag?post=9551"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}