{"id":6731,"date":"2022-04-08T08:21:56","date_gmt":"2022-04-08T08:21:56","guid":{"rendered":"https:\/\/jordibordas.com\/z\/?page_id=6731"},"modified":"2023-05-30T13:32:51","modified_gmt":"2023-05-30T11:32:51","slug":"mis-cursos","status":"publish","type":"page","link":"https:\/\/jordibordas.com\/z\/mis-cursos\/","title":{"rendered":"Mis cursos"},"content":{"rendered":"<div class=\"wp-block-sensei-lms-learner-courses wp-block-sensei-lms-learner-courses  has-sensei-progress-bar-height  has-sensei-progress-bar-border-radius  wp-block-sensei-lms-learner-courses--is-list-view \" style=\"\">\t\t<div id=\"my-courses\">\n\t\t\t\t\t\t<div class=\"col2-set\" id=\"customer_login\">\n\n\t\t\t\t<div class=\"col-1\">\n\t\t\t\t\t\n<h2>Acceder<\/h2>\n\n<form method=\"post\" name=\"sensi-login-form\" id=\"loginform\" class=\"login sensei\">\n\n\t\n\t<p class=\"sensei-login-username form-row form-row-wide\">\n\n\t\t\t\t<label for=\"sensei_user_login\">Usuario o correo electr\u00f3nico <\/label>\n\n\t\t\t\t<input type=\"text\" name=\"log\" id=\"sensei_user_login\" class=\"input input-text\" value=\"\" size=\"20\">\n\n\t<\/p>\n\n\t<p class=\"sensei-login-password form-row form-row-wide\">\n\n\t\t\t\t<label for=\"sensei_user_pass\"> Contrase\u00f1a  <\/label>\n\n\t\t\t\t<input type=\"password\" name=\"pwd\" id=\"sensei_user_pass\" class=\"input txt text input-text\" value=\"\" size=\"20\">\n\n\t<\/p>\n\n\t\n\t<p class='sensei-login-submit'>\n\n\t\t<input type=\"submit\" class=\"button wp-element-button\" name=\"login\" value=\"Acceder\" \/>\n\n\t\t<a href=\"https:\/\/jordibordas.com\/z\/mi-cuenta\/lost-password\/\">\u00bfHas perdido tu contrase\u00f1a?<\/a>\n\n\t<\/p>\n\n\t<p class='remember_me' >\n\n\t\t<label for=\"rememberme\" class=\"inline\">\n\n\t\t\t<input name=\"rememberme\" type=\"checkbox\" id=\"rememberme\" value=\"forever\" \/> Recu\u00e9rdame\n\t\t<\/label>\n\n\t<\/p>\n\n\t\n\t<input type=\"hidden\" id=\"_wpnonce\" name=\"_wpnonce\" value=\"49ef07f64c\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/z\/wp-json\/wp\/v2\/pages\/6731\" \/>\n\t<input type=\"hidden\" name=\"redirect\" value=\"https:\/\/jordibordas.com\/z\/wp-json\/wp\/v2\/pages\/6731\" \/>\n\n\t<input type=\"hidden\" name=\"form\" value=\"sensei-login\" \/>\n\n\t<div class=\"clear\"><\/div>\n\n<\/form>\n\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/template-my-courses.php","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"class_list":["post-6731","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mis cursos - Innovative Pastry Education<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jordibordas.com\/z\/mis-cursos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mis cursos - Innovative Pastry Education\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jordibordas.com\/z\/mis-cursos\/\" \/>\n<meta property=\"og:site_name\" content=\"Innovative Pastry Education\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-30T11:32:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jordibordas.com\\\/z\\\/mis-cursos\\\/\",\"url\":\"https:\\\/\\\/jordibordas.com\\\/z\\\/mis-cursos\\\/\",\"name\":\"Mis cursos - Innovative Pastry Education\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jordibordas.com\\\/z\\\/#website\"},\"datePublished\":\"2022-04-08T08:21:56+00:00\",\"dateModified\":\"2023-05-30T11:32:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jordibordas.com\\\/z\\\/mis-cursos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jordibordas.com\\\/z\\\/mis-cursos\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jordibordas.com\\\/z\\\/mis-cursos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/jordibordas.com\\\/z\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mis cursos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jordibordas.com\\\/z\\\/#website\",\"url\":\"https:\\\/\\\/jordibordas.com\\\/z\\\/\",\"name\":\"Innovative Pastry Education\",\"description\":\"Innovative Pastry Education\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jordibordas.com\\\/z\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mis cursos - Innovative Pastry Education","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jordibordas.com\/z\/mis-cursos\/","og_locale":"es_ES","og_type":"article","og_title":"Mis cursos - Innovative Pastry Education","og_url":"https:\/\/jordibordas.com\/z\/mis-cursos\/","og_site_name":"Innovative Pastry Education","article_modified_time":"2023-05-30T11:32:51+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/jordibordas.com\/z\/mis-cursos\/","url":"https:\/\/jordibordas.com\/z\/mis-cursos\/","name":"Mis cursos - Innovative Pastry Education","isPartOf":{"@id":"https:\/\/jordibordas.com\/z\/#website"},"datePublished":"2022-04-08T08:21:56+00:00","dateModified":"2023-05-30T11:32:51+00:00","breadcrumb":{"@id":"https:\/\/jordibordas.com\/z\/mis-cursos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jordibordas.com\/z\/mis-cursos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/jordibordas.com\/z\/mis-cursos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/jordibordas.com\/z\/"},{"@type":"ListItem","position":2,"name":"Mis cursos"}]},{"@type":"WebSite","@id":"https:\/\/jordibordas.com\/z\/#website","url":"https:\/\/jordibordas.com\/z\/","name":"Innovative Pastry Education","description":"Innovative Pastry Education","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jordibordas.com\/z\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/jordibordas.com\/z\/wp-json\/wp\/v2\/pages\/6731","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jordibordas.com\/z\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/jordibordas.com\/z\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/jordibordas.com\/z\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/jordibordas.com\/z\/wp-json\/wp\/v2\/comments?post=6731"}],"version-history":[{"count":7,"href":"https:\/\/jordibordas.com\/z\/wp-json\/wp\/v2\/pages\/6731\/revisions"}],"predecessor-version":[{"id":8532,"href":"https:\/\/jordibordas.com\/z\/wp-json\/wp\/v2\/pages\/6731\/revisions\/8532"}],"wp:attachment":[{"href":"https:\/\/jordibordas.com\/z\/wp-json\/wp\/v2\/media?parent=6731"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}